{"id":16837,"date":"2025-10-06T10:17:27","date_gmt":"2025-10-06T08:17:27","guid":{"rendered":"https:\/\/bodegascerda.com\/?post_type=product&#038;p=16837"},"modified":"2025-10-06T10:17:28","modified_gmt":"2025-10-06T08:17:28","slug":"bolsa-de-rafia-para-2-botellas","status":"publish","type":"product","link":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/","title":{"rendered":"Bolsa de rafia para 2 botellas"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":16838,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[223],"product_tag":[],"class_list":{"0":"post-16837","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolsa de rafia para 2 botellas - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsa de rafia para 2 botellas - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/\" \/>\n<meta property=\"og:site_name\" content=\"Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bodegas.cerda.hondon\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T08:17:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/10\/Bolsa_Rafia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"10,00&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/\",\"name\":\"Bolsa de rafia para 2 botellas - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bolsa_Rafia.jpg\",\"datePublished\":\"2025-10-06T08:17:27+00:00\",\"dateModified\":\"2025-10-06T08:17:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bolsa_Rafia.jpg\",\"contentUrl\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bolsa_Rafia.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Bolsa de rafia para 2 botellas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bolsa de rafia para 2 botellas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/\",\"name\":\"Bodegas Cerd\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/#organization\",\"name\":\"Bodegas Cerd\u00e1 Cremades, S.L.\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bodegas.cerda.hondon\",\"https:\\\/\\\/www.instagram.com\\\/bodegas.cerda\\\/\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/en\\\/product\\\/bolsa-de-rafia-para-2-botellas\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-bodegas-cerda.png\",\"contentUrl\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-bodegas-cerda.png\",\"width\":192,\"height\":100,\"caption\":\"Bodegas Cerd\u00e1 Cremades, S.L.\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"10.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsa de rafia para 2 botellas - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/","og_locale":"en_US","og_type":"article","og_title":"Bolsa de rafia para 2 botellas - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1","og_url":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/","og_site_name":"Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1","article_publisher":"https:\/\/www.facebook.com\/bodegas.cerda.hondon","article_modified_time":"2025-10-06T08:17:28+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/10\/Bolsa_Rafia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"10,00&euro;","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/","url":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/","name":"Bolsa de rafia para 2 botellas - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1","isPartOf":{"@id":"https:\/\/bodegascerda.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/#primaryimage"},"image":{"@id":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/#primaryimage"},"thumbnailUrl":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/10\/Bolsa_Rafia.jpg","datePublished":"2025-10-06T08:17:27+00:00","dateModified":"2025-10-06T08:17:28+00:00","breadcrumb":{"@id":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/#primaryimage","url":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/10\/Bolsa_Rafia.jpg","contentUrl":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/10\/Bolsa_Rafia.jpg","width":1000,"height":1000,"caption":"Bolsa de rafia para 2 botellas"},{"@type":"BreadcrumbList","@id":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bodegascerda.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/bodegascerda.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Bolsa de rafia para 2 botellas"}]},{"@type":"WebSite","@id":"https:\/\/bodegascerda.com\/en\/#website","url":"https:\/\/bodegascerda.com\/en\/","name":"Bodegas Cerd\u00e1","description":"","publisher":{"@id":"https:\/\/bodegascerda.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bodegascerda.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/bodegascerda.com\/en\/#organization","name":"Bodegas Cerd\u00e1 Cremades, S.L.","url":"https:\/\/bodegascerda.com\/en\/","logo":{"@id":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/#local-main-organization-logo"},"image":{"@id":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/bodegas.cerda.hondon","https:\/\/www.instagram.com\/bodegas.cerda\/"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bodegascerda.com\/en\/product\/bolsa-de-rafia-para-2-botellas\/#local-main-organization-logo","url":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/05\/logo-bodegas-cerda.png","contentUrl":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/05\/logo-bodegas-cerda.png","width":192,"height":100,"caption":"Bodegas Cerd\u00e1 Cremades, S.L."}]},"product_price_amount":"10.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/bodegascerda.com\/en\/wp-json\/wp\/v2\/product\/16837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodegascerda.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bodegascerda.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bodegascerda.com\/en\/wp-json\/wp\/v2\/media\/16838"}],"wp:attachment":[{"href":"https:\/\/bodegascerda.com\/en\/wp-json\/wp\/v2\/media?parent=16837"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bodegascerda.com\/en\/wp-json\/wp\/v2\/product_brand?post=16837"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bodegascerda.com\/en\/wp-json\/wp\/v2\/product_cat?post=16837"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bodegascerda.com\/en\/wp-json\/wp\/v2\/product_tag?post=16837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}