{"id":9328,"date":"2023-04-04T06:53:05","date_gmt":"2023-04-04T04:53:05","guid":{"rendered":"https:\/\/bodegascerda.com\/product\/cerda-autor-04-rosado-monastrell\/"},"modified":"2025-05-17T10:49:56","modified_gmt":"2025-05-17T08:49:56","slug":"cerda-autor-04-rosado-monastrell","status":"publish","type":"product","link":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/","title":{"rendered":"Cerd\u00e1 Autor 04 &#8211; Rosado Monastrell"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong class=\"dorado\">&#8211;<\/strong> Traube: Monastrell.<br \/>\n<strong class=\"dorado\">&#8211;<\/strong> Aussehen:zweiebelschalenfarben mit rosefarbenem Glitzer.<br \/>\n<strong class=\"dorado\">&#8211;<\/strong> Aroma: frisch,fruchtig.<br \/>\n<strong class=\"dorado\">&#8211;<\/strong> Temperatur: Zwischen 6 bis 8 Grad.<br \/>\n<strong class=\"dorado\">&#8211;<\/strong> Geschmack: fruchtig,frisch mit feine S\u00e4ure.<br \/>\n<strong class=\"dorado\">&#8211;<\/strong> Passt zu: Fisch,Reis und Salat.<br \/>\n<strong class=\"dorado\">&#8211;<\/strong> Lagerung: keine Lagerung in der Bodega<br \/>\n<strong class=\"dorado\">&#8211;<\/strong> Verzehr: Mindesthaltbarkeit bis zwei Jahre.<br \/>\n<strong class=\"dorado\">&#8211;<\/strong> Alkohol: 12.5Volume.<\/p>\n","protected":false},"featured_media":6921,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[140,144],"product_tag":[139],"class_list":{"0":"post-9328","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-rose","7":"product_cat-vino-de-autor","8":"product_tag-de-2","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cerd\u00e1 Autor 04 - Rosado Monastrell - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cerd\u00e1 Autor 04 - Rosado Monastrell - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1\" \/>\n<meta property=\"og:description\" content=\"- Traube: Monastrell. - Aussehen:zweiebelschalenfarben mit rosefarbenem Glitzer. - Aroma: frisch,fruchtig. - Temperatur: Zwischen 6 bis 8 Grad. - Geschmack: fruchtig,frisch mit feine S\u00e4ure. - Passt zu: Fisch,Reis und Salat. - Lagerung: keine Lagerung in der Bodega - Verzehr: Mindesthaltbarkeit bis zwei Jahre. - Alkohol: 12.5Volume.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/\" \/>\n<meta property=\"og:site_name\" content=\"Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bodegas.cerda.hondon\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-17T08:49:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/05\/cerda-autor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"12,00&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/\",\"name\":\"Cerd\u00e1 Autor 04 - Rosado Monastrell - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cerda-autor.jpg\",\"datePublished\":\"2023-04-04T04:53:05+00:00\",\"dateModified\":\"2025-05-17T08:49:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cerda-autor.jpg\",\"contentUrl\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cerda-autor.jpg\",\"width\":800,\"height\":800,\"caption\":\"Vino de Autor Cerd\u00e1 04\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cerd\u00e1 Autor 04 &#8211; Rosado Monastrell\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/\",\"name\":\"Bodegas Cerd\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/#organization\",\"name\":\"Bodegas Cerd\u00e1 Cremades, S.L.\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bodegas.cerda.hondon\",\"https:\\\/\\\/www.instagram.com\\\/bodegas.cerda\\\/\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bodegascerda.com\\\/de\\\/product\\\/cerda-autor-04-rosado-monastrell\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-bodegas-cerda.png\",\"contentUrl\":\"https:\\\/\\\/bodegascerda.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-bodegas-cerda.png\",\"width\":192,\"height\":100,\"caption\":\"Bodegas Cerd\u00e1 Cremades, S.L.\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerd\u00e1 Autor 04 - Rosado Monastrell - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/","og_locale":"de_DE","og_type":"article","og_title":"Cerd\u00e1 Autor 04 - Rosado Monastrell - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1","og_description":"- Traube: Monastrell. - Aussehen:zweiebelschalenfarben mit rosefarbenem Glitzer. - Aroma: frisch,fruchtig. - Temperatur: Zwischen 6 bis 8 Grad. - Geschmack: fruchtig,frisch mit feine S\u00e4ure. - Passt zu: Fisch,Reis und Salat. - Lagerung: keine Lagerung in der Bodega - Verzehr: Mindesthaltbarkeit bis zwei Jahre. - Alkohol: 12.5Volume.","og_url":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/","og_site_name":"Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1","article_publisher":"https:\/\/www.facebook.com\/bodegas.cerda.hondon","article_modified_time":"2025-05-17T08:49:56+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/05\/cerda-autor.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"12,00&euro;","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/","url":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/","name":"Cerd\u00e1 Autor 04 - Rosado Monastrell - Bodega de vino en Alicante, cerca de Elche, desde 1885 | Bodegas Cerd\u00e1","isPartOf":{"@id":"https:\/\/bodegascerda.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/#primaryimage"},"image":{"@id":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/#primaryimage"},"thumbnailUrl":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/05\/cerda-autor.jpg","datePublished":"2023-04-04T04:53:05+00:00","dateModified":"2025-05-17T08:49:56+00:00","breadcrumb":{"@id":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/#primaryimage","url":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/05\/cerda-autor.jpg","contentUrl":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/05\/cerda-autor.jpg","width":800,"height":800,"caption":"Vino de Autor Cerd\u00e1 04"},{"@type":"BreadcrumbList","@id":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bodegascerda.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/bodegascerda.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Cerd\u00e1 Autor 04 &#8211; Rosado Monastrell"}]},{"@type":"WebSite","@id":"https:\/\/bodegascerda.com\/de\/#website","url":"https:\/\/bodegascerda.com\/de\/","name":"Bodegas Cerd\u00e1","description":"","publisher":{"@id":"https:\/\/bodegascerda.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bodegascerda.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/bodegascerda.com\/de\/#organization","name":"Bodegas Cerd\u00e1 Cremades, S.L.","url":"https:\/\/bodegascerda.com\/de\/","logo":{"@id":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/#local-main-organization-logo"},"image":{"@id":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/bodegas.cerda.hondon","https:\/\/www.instagram.com\/bodegas.cerda\/"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bodegascerda.com\/de\/product\/cerda-autor-04-rosado-monastrell\/#local-main-organization-logo","url":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/05\/logo-bodegas-cerda.png","contentUrl":"https:\/\/bodegascerda.com\/wp-content\/uploads\/2025\/05\/logo-bodegas-cerda.png","width":192,"height":100,"caption":"Bodegas Cerd\u00e1 Cremades, S.L."}]},"product_price_amount":"12.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/bodegascerda.com\/de\/wp-json\/wp\/v2\/product\/9328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodegascerda.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bodegascerda.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bodegascerda.com\/de\/wp-json\/wp\/v2\/media\/6921"}],"wp:attachment":[{"href":"https:\/\/bodegascerda.com\/de\/wp-json\/wp\/v2\/media?parent=9328"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bodegascerda.com\/de\/wp-json\/wp\/v2\/product_brand?post=9328"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bodegascerda.com\/de\/wp-json\/wp\/v2\/product_cat?post=9328"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bodegascerda.com\/de\/wp-json\/wp\/v2\/product_tag?post=9328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}